{"id":121843,"date":"2023-08-24T00:01:29","date_gmt":"2023-08-24T03:01:29","guid":{"rendered":"http:\/\/vagario.com.br\/?p=121843"},"modified":"2023-08-23T20:40:49","modified_gmt":"2023-08-23T23:40:49","slug":"atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas","status":"publish","type":"post","link":"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/","title":{"rendered":"Atendente \u2013 Loja de Sapatos \u2013 Madureira \u2013 R$ 1.310,00 \u2013 3 vagas"},"content":{"rendered":"<p><span style=\"font-family: 'arial black', sans-serif;\"><strong>REQUERIMENTOS E INFORMA\u00c7\u00d5ES DA VAGA:<\/strong><\/span><\/p>\n<p data-original-attrs=\"{&quot;style&quot;:&quot;mso-margin-bottom-alt: auto; mso-margin-top-alt: auto; tab-stops: 45.8pt 91.6pt 137.4pt 183.2pt 229.0pt 274.8pt 320.6pt 366.4pt 412.2pt 458.0pt 503.8pt 549.6pt 595.4pt 641.2pt 687.0pt 732.8pt;&quot;}\">Cargo \u2013<strong>\u00a0Atendente de Loja<\/strong><\/p>\n<p data-original-attrs=\"{&quot;style&quot;:&quot;mso-margin-bottom-alt: auto; mso-margin-top-alt: auto; tab-stops: 45.8pt 91.6pt 137.4pt 183.2pt 229.0pt 274.8pt 320.6pt 366.4pt 412.2pt 458.0pt 503.8pt 549.6pt 595.4pt 641.2pt 687.0pt 732.8pt;&quot;}\"><strong>Quantidade de vagas \u2013 3<\/strong><\/p>\n<p data-original-attrs=\"{&quot;style&quot;:&quot;mso-margin-bottom-alt: auto; mso-margin-top-alt: auto; tab-stops: 45.8pt 91.6pt 137.4pt 183.2pt 229.0pt 274.8pt 320.6pt 366.4pt 412.2pt 458.0pt 503.8pt 549.6pt 595.4pt 641.2pt 687.0pt 732.8pt;&quot;}\"><strong>Quantidade de candidatos, no perfil, que ser\u00e3o encaminhados para entrevista \u2013 3<\/strong><\/p>\n<p data-original-attrs=\"{&quot;style&quot;:&quot;mso-margin-bottom-alt: auto; mso-margin-top-alt: auto; tab-stops: 45.8pt 91.6pt 137.4pt 183.2pt 229.0pt 274.8pt 320.6pt 366.4pt 412.2pt 458.0pt 503.8pt 549.6pt 595.4pt 641.2pt 687.0pt 732.8pt;&quot;}\">Empresa Contratante \u2013 Servi\u00e7os<\/p>\n<p data-original-attrs=\"{&quot;style&quot;:&quot;mso-margin-bottom-alt: auto; mso-margin-top-alt: auto; tab-stops: 45.8pt 91.6pt 137.4pt 183.2pt 229.0pt 274.8pt 320.6pt 366.4pt 412.2pt 458.0pt 503.8pt 549.6pt 595.4pt 641.2pt 687.0pt 732.8pt;&quot;}\">Local de Trabalho:<\/p>\n<ul>\n<li>Cidade do Rio de Janeiro \u2013 Madureira<\/li>\n<\/ul>\n<p>Sal\u00e1rio \u2013 R$ 1.310,00 + benef\u00edcios<\/p>\n<p>Regime de contrata\u00e7\u00e3o \u2013 CLT (carteira assinada)<\/p>\n<p data-original-attrs=\"{&quot;style&quot;:&quot;mso-margin-bottom-alt: auto; mso-margin-top-alt: auto; tab-stops: 45.8pt 91.6pt 137.4pt 183.2pt 229.0pt 274.8pt 320.6pt 366.4pt 412.2pt 458.0pt 503.8pt 549.6pt 595.4pt 641.2pt 687.0pt 732.8pt;&quot;}\">Requisitos:<\/p>\n<ul>\n<li>Ensino m\u00e9dio completo<\/li>\n<li>Aceita candidatos sem experi\u00eancia anterior<\/li>\n<\/ul>\n<p><span style=\"font-family: 'arial black', sans-serif;\"><strong>CADASTRE O SEU CURR\u00cdCULO:<\/strong><\/span><br \/>\n<input type='hidden' bg_collapse_expand='6a047104460c14056435501' value='6a047104460c14056435501'><input type='hidden' id='bg-show-more-text-6a047104460c14056435501' value='Quero me Candidatar'><input type='hidden' id='bg-show-less-text-6a047104460c14056435501' value='Fechar'><button id='bg-showmore-action-6a047104460c14056435501' class='bg-showmore-plg-button bg-orange-button  '   style=\" color:#4a4949;\">Quero me Candidatar<\/button><div id='bg-showmore-hidden-6a047104460c14056435501' >Para se candidatar a vaga clique em:\u00a0 <a href=\"mailto:cadastrogrupoac@yahoo.com.br\">cadastrogrupoac@yahoo.com.br<\/a>\u00a0 <\/div>\n<p><a href=\"https:\/\/youtube.com\/@cariocaempregos\"><strong>Para mais Vagas se inscreva e acesse o nosso Canal no Youtube clicando aqui!<\/strong><\/a><\/p>\n<p><strong>LEIA COM ATEN\u00c7\u00c3O!<\/strong><\/p>\n<h3><a href=\"https:\/\/vagario.com.br\/index.php\/grupo-de-empregos-no-whatsapp\/\"><strong>Entre para o nosso grupo de emprego no Whatsapp clicando aqui!<\/strong><\/a><\/h3>\n<p><em><strong>Todas as vagas aqui publicadas como informamos em nossos termos de uso, s\u00e3o de COMPLETA RESPONSABILIDADE dos contratantes\/anunciantes, O RJ VAGAS<\/strong><\/em><em><strong>\u00a0n\u00e3o<\/strong><\/em><em><strong>\u00a0 entra em contato com nenhuma empresa para verificar a veracidade das informa\u00e7\u00f5es fornecidas, a responsabilidade da verifica\u00e7\u00e3o das informa\u00e7\u00f5es e demais d\u00favidas das vagas \u00e9 do candidato interessado.<\/strong><\/em><\/p>\n<p><a href=\"whatsapp:\/\/send?text=&quot;RioVaga - Empregos e Vagas Rio de Janeiro - Clique no link para instalar e se candidatar as vagas:&quot;https:\/\/play.google.com\/store\/apps\/details?id=com.riovagaaa\"><br \/>\nCompartilhe essa vaga com um amigo do Whatsapp &#8211; Clicando Aqui!!<br \/>\n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>REQUERIMENTOS E INFORMA\u00c7\u00d5ES DA VAGA: Cargo \u2013\u00a0Atendente de Loja Quantidade de vagas \u2013 3 Quantidade de candidatos, no perfil, que<\/p>\n","protected":false},"author":1,"featured_media":115416,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-121843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atendente-balconistas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Atendente \u2013 Loja de Sapatos \u2013 Madureira \u2013 R$ 1.310,00 \u2013 3 vagas<\/title>\n<meta name=\"description\" content=\"Atendente \u2013 Loja de Sapatos \u2013 Madureira \u2013 R$ 1.310,00 \u2013 3 vagas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atendente \u2013 Loja de Sapatos \u2013 Madureira \u2013 R$ 1.310,00 \u2013 3 vagas\" \/>\n<meta property=\"og:description\" content=\"Atendente \u2013 Loja de Sapatos \u2013 Madureira \u2013 R$ 1.310,00 \u2013 3 vagas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/\" \/>\n<meta property=\"og:site_name\" content=\"Vagario\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-24T03:01:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vagario.com.br\/wp-content\/uploads\/2021\/01\/5.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"vagario\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vagario\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/\"},\"author\":{\"name\":\"vagario\",\"@id\":\"https:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6\"},\"headline\":\"Atendente \u2013 Loja de Sapatos \u2013 Madureira \u2013 R$ 1.310,00 \u2013 3 vagas\",\"datePublished\":\"2023-08-24T03:01:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/\"},\"wordCount\":195,\"publisher\":{\"@id\":\"https:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6\"},\"image\":{\"@id\":\"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/vagario.com.br\/wp-content\/uploads\/2021\/01\/5.png\",\"articleSection\":[\"Atendente \/ Balconistas\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/\",\"url\":\"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/\",\"name\":\"Atendente \u2013 Loja de Sapatos \u2013 Madureira \u2013 R$ 1.310,00 \u2013 3 vagas\",\"isPartOf\":{\"@id\":\"https:\/\/vagario.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/vagario.com.br\/wp-content\/uploads\/2021\/01\/5.png\",\"datePublished\":\"2023-08-24T03:01:29+00:00\",\"description\":\"Atendente \u2013 Loja de Sapatos \u2013 Madureira \u2013 R$ 1.310,00 \u2013 3 vagas\",\"breadcrumb\":{\"@id\":\"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/#primaryimage\",\"url\":\"https:\/\/vagario.com.br\/wp-content\/uploads\/2021\/01\/5.png\",\"contentUrl\":\"https:\/\/vagario.com.br\/wp-content\/uploads\/2021\/01\/5.png\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/vagario.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atendente \u2013 Loja de Sapatos \u2013 Madureira \u2013 R$ 1.310,00 \u2013 3 vagas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vagario.com.br\/#website\",\"url\":\"https:\/\/vagario.com.br\/\",\"name\":\"Vagario\",\"description\":\"Seu Melhor site de Empregos e Vagas\",\"publisher\":{\"@id\":\"https:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/vagario.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6\",\"name\":\"vagario\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/vagario.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/83c677ba6122e98ab37e1afa2508ddf0de0cec8e3065582b3e503ef328b5b67a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/83c677ba6122e98ab37e1afa2508ddf0de0cec8e3065582b3e503ef328b5b67a?s=96&d=mm&r=g\",\"caption\":\"vagario\"},\"logo\":{\"@id\":\"https:\/\/vagario.com.br\/#\/schema\/person\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atendente \u2013 Loja de Sapatos \u2013 Madureira \u2013 R$ 1.310,00 \u2013 3 vagas","description":"Atendente \u2013 Loja de Sapatos \u2013 Madureira \u2013 R$ 1.310,00 \u2013 3 vagas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/","og_locale":"pt_BR","og_type":"article","og_title":"Atendente \u2013 Loja de Sapatos \u2013 Madureira \u2013 R$ 1.310,00 \u2013 3 vagas","og_description":"Atendente \u2013 Loja de Sapatos \u2013 Madureira \u2013 R$ 1.310,00 \u2013 3 vagas","og_url":"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/","og_site_name":"Vagario","article_published_time":"2023-08-24T03:01:29+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/vagario.com.br\/wp-content\/uploads\/2021\/01\/5.png","type":"image\/png"}],"author":"vagario","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"vagario","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/#article","isPartOf":{"@id":"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/"},"author":{"name":"vagario","@id":"https:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6"},"headline":"Atendente \u2013 Loja de Sapatos \u2013 Madureira \u2013 R$ 1.310,00 \u2013 3 vagas","datePublished":"2023-08-24T03:01:29+00:00","mainEntityOfPage":{"@id":"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/"},"wordCount":195,"publisher":{"@id":"https:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6"},"image":{"@id":"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/#primaryimage"},"thumbnailUrl":"https:\/\/vagario.com.br\/wp-content\/uploads\/2021\/01\/5.png","articleSection":["Atendente \/ Balconistas"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/","url":"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/","name":"Atendente \u2013 Loja de Sapatos \u2013 Madureira \u2013 R$ 1.310,00 \u2013 3 vagas","isPartOf":{"@id":"https:\/\/vagario.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/#primaryimage"},"image":{"@id":"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/#primaryimage"},"thumbnailUrl":"https:\/\/vagario.com.br\/wp-content\/uploads\/2021\/01\/5.png","datePublished":"2023-08-24T03:01:29+00:00","description":"Atendente \u2013 Loja de Sapatos \u2013 Madureira \u2013 R$ 1.310,00 \u2013 3 vagas","breadcrumb":{"@id":"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/#primaryimage","url":"https:\/\/vagario.com.br\/wp-content\/uploads\/2021\/01\/5.png","contentUrl":"https:\/\/vagario.com.br\/wp-content\/uploads\/2021\/01\/5.png","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/vagario.com.br\/index.php\/2023\/08\/24\/atendente-loja-de-sapatos-madureira-r-1-31000-3-vagas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/vagario.com.br\/"},{"@type":"ListItem","position":2,"name":"Atendente \u2013 Loja de Sapatos \u2013 Madureira \u2013 R$ 1.310,00 \u2013 3 vagas"}]},{"@type":"WebSite","@id":"https:\/\/vagario.com.br\/#website","url":"https:\/\/vagario.com.br\/","name":"Vagario","description":"Seu Melhor site de Empregos e Vagas","publisher":{"@id":"https:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vagario.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6","name":"vagario","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/vagario.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/83c677ba6122e98ab37e1afa2508ddf0de0cec8e3065582b3e503ef328b5b67a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83c677ba6122e98ab37e1afa2508ddf0de0cec8e3065582b3e503ef328b5b67a?s=96&d=mm&r=g","caption":"vagario"},"logo":{"@id":"https:\/\/vagario.com.br\/#\/schema\/person\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/121843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=121843"}],"version-history":[{"count":3,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/121843\/revisions"}],"predecessor-version":[{"id":123861,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/121843\/revisions\/123861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/media\/115416"}],"wp:attachment":[{"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=121843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=121843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=121843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}