{"id":116060,"date":"2021-03-03T10:12:03","date_gmt":"2021-03-03T13:12:03","guid":{"rendered":"http:\/\/vagario.com.br\/?p=116060"},"modified":"2021-03-03T10:12:03","modified_gmt":"2021-03-03T13:12:03","slug":"prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj","status":"publish","type":"post","link":"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/","title":{"rendered":"PREZUNIC ABRE VAGAS &#8211; ATENDENTES &#8211; 4 VAGAS &#8211; RIO DE JANEIRO &#8211; RJ"},"content":{"rendered":"<p><span style=\"font-family: 'arial black', sans-serif;\"><strong>REQUERIMENTOS E INFORMA\u00c7\u00d5ES DA VAGA:<\/strong><\/span><\/p>\n<p>O que voc\u00ea ter\u00e1 de responsabilidade:<\/p>\n<p>\u2013 Registrar as mercadorias dos clientes, pesando-os quando necess\u00e1rios, garantindo a movimenta\u00e7\u00e3o do caixa com exatid\u00e3o nas informa\u00e7\u00f5es dos valores envolvidos na compra<\/p>\n<p>\u2013 Manter o local de trabalho sempre limpo e organizado garantindo a qualidade no atendimento e a conserva\u00e7\u00e3o do check out<\/p>\n<p>\u2013 Memorizar os c\u00f3digos de barra de determinados produtos, objetivando agilidade nos registros das mercadorias, garantindo a qualidade no atendimento<\/p>\n<p>\u2013 Solicitar troco ao Fiscal de Atendimento, quando necess\u00e1rio, com objetivo de manter o troco sempre adequado para atender \u00e1 demanda dos clientes da regi\u00e3o<\/p>\n<p>\u2013 Receber com seguran\u00e7a e cordialidade os pagamentos efetuados, identificando cheques suspeitos e notas falsas, solicitando \u00e0 chefia sem que haja um comprometimento no atendimento<\/p>\n<p>\u2013 Reportar \u00e0 chefia sempre que houver problemas com PDV, balan\u00e7as, c\u00f3digos ou pre\u00e7os errados, identificando o problema corretamente, objetivando a qualidade no atendimento<\/p>\n<p>\u2013 Solicitar com cordialidade e habilidade com o p\u00fablico, documentos para confer\u00eancia de cheques, assegurando a venda<\/p>\n<p>\u2013 Preparar sangria de valores para que no ato da sangria n\u00e3o haja um comprometimento no atendimento<\/p>\n<p>\u2013 Conferir o troco, ao abrir o Caixa, comunicando poss\u00edveis diferen\u00e7as ao Fiscal de Atendimento, assegurando os servi\u00e7os prestados<\/p>\n<p>\u2013 Fiscalizar os pre\u00e7os dos Setores, comunicando aos respons\u00e1veis pelo Setor caso haja poss\u00edveis erros na coloca\u00e7\u00e3o dos pre\u00e7os<\/p>\n<p>O que buscamos em voc\u00ea:<br \/>\n\u2013 Forma\u00e7\u00e3o: Ensino M\u00e9dio completo.<br \/>\n\u2013 Pontualidade e comprometimento.<br \/>\n\u2013 Agilidade e aten\u00e7\u00e3o.<\/p>\n<p>O que iremos te oferecer:<br \/>\n\u2013 Benef\u00edcios compat\u00edveis com empresa de grande porte<\/p>\n<p>\u2013 Oportunidade de crescimento profissional<\/p>\n<p>Rio de Janeiro \/ RJ<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: 'arial black', sans-serif;\"><strong>CADASTRE O SEU CURR\u00cdCULO:<\/strong><\/span><br \/>\n<input type='hidden' bg_collapse_expand='6a04dc9c841817014724622' value='6a04dc9c841817014724622'><input type='hidden' id='bg-show-more-text-6a04dc9c841817014724622' value='Quero me Candidatar'><input type='hidden' id='bg-show-less-text-6a04dc9c841817014724622' value='Fechar'><button id='bg-showmore-action-6a04dc9c841817014724622' class='bg-showmore-plg-button bg-orange-button  '   style=\" color:#4a4949;\">Quero me Candidatar<\/button><div id='bg-showmore-hidden-6a04dc9c841817014724622' >Para se candidatar a vaga clique em: <a href=\"https:\/\/site.vagas.com.br\/PagVagaDirSS.asp?v=2171952&amp;pp=https%3A\/\/site.vagas.com.br\/GoHome.asp%3Fv%3D2171952%26fnthr%3Dhttps%253A\/\/rjempregos.net\/%26j%3Dt%26sslon%3D1&amp;wiw=1366\">vagas.com.br<\/a> <\/div>\n<h6><\/h6>\n<p><em><strong>Todas as vagas aqui publicadas como informamos em nossos termos de uso, s\u00e3o de COMPLETA RESPONSABILIDADE dos contratantes\/anunciantes, O RIOVAGA RJ<\/strong><\/em><em><strong>\u00a0n\u00e3o<\/strong><\/em><em><strong>\u00a0 entra em contato com nenhuma empresa para verificar a veracidade das informa\u00e7\u00f5es fornecidas, a responsabilidade da verifica\u00e7\u00e3o das informa\u00e7\u00f5es e demais d\u00favidas das vagas \u00e9 do candidato interessado.<\/strong><\/em><\/p>\n<p><a href=\"whatsapp:\/\/send?text=&quot;RioVaga - Empregos e Vagas Rio de Janeiro - Clique no link para instalar e se candidatar as vagas:&quot;https:\/\/play.google.com\/store\/apps\/details?id=com.riovagaaa\"><br \/>\nCompartilhe essa vaga com um amigo do Whatsapp &#8211; Clicando Aqui!!<br \/>\n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>REQUERIMENTOS E INFORMA\u00c7\u00d5ES DA VAGA: O que voc\u00ea ter\u00e1 de responsabilidade: \u2013 Registrar as mercadorias dos clientes, pesando-os quando necess\u00e1rios,<\/p>\n","protected":false},"author":1,"featured_media":115416,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-116060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atendente-balconistas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PREZUNIC ABRE VAGAS - ATENDENTES - 4 VAGAS - RIO DE JANEIRO - RJ<\/title>\n<meta name=\"description\" content=\"PREZUNIC ABRE VAGAS - ATENDENTES - 4 VAGAS - RIO DE JANEIRO - RJ\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PREZUNIC ABRE VAGAS - ATENDENTES - 4 VAGAS - RIO DE JANEIRO - RJ\" \/>\n<meta property=\"og:description\" content=\"PREZUNIC ABRE VAGAS - ATENDENTES - 4 VAGAS - RIO DE JANEIRO - RJ\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/\" \/>\n<meta property=\"og:site_name\" content=\"Vagario\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-03T13:12:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vagario.com.br\/wp-content\/uploads\/2019\/12\/carioca256-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"256\" \/>\n\t<meta property=\"og:image:height\" content=\"256\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"vagario\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vagario\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/\"},\"author\":{\"name\":\"vagario\",\"@id\":\"https:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6\"},\"headline\":\"PREZUNIC ABRE VAGAS &#8211; ATENDENTES &#8211; 4 VAGAS &#8211; RIO DE JANEIRO &#8211; RJ\",\"datePublished\":\"2021-03-03T13:12:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/\"},\"wordCount\":384,\"publisher\":{\"@id\":\"https:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6\"},\"image\":{\"@id\":\"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/vagario.com.br\/wp-content\/uploads\/2021\/01\/5.png\",\"articleSection\":[\"Atendente \/ Balconistas\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/\",\"url\":\"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/\",\"name\":\"PREZUNIC ABRE VAGAS - ATENDENTES - 4 VAGAS - RIO DE JANEIRO - RJ\",\"isPartOf\":{\"@id\":\"https:\/\/vagario.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/vagario.com.br\/wp-content\/uploads\/2021\/01\/5.png\",\"datePublished\":\"2021-03-03T13:12:03+00:00\",\"description\":\"PREZUNIC ABRE VAGAS - ATENDENTES - 4 VAGAS - RIO DE JANEIRO - RJ\",\"breadcrumb\":{\"@id\":\"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/#primaryimage\",\"url\":\"https:\/\/vagario.com.br\/wp-content\/uploads\/2021\/01\/5.png\",\"contentUrl\":\"https:\/\/vagario.com.br\/wp-content\/uploads\/2021\/01\/5.png\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/vagario.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PREZUNIC ABRE VAGAS &#8211; ATENDENTES &#8211; 4 VAGAS &#8211; RIO DE JANEIRO &#8211; RJ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vagario.com.br\/#website\",\"url\":\"https:\/\/vagario.com.br\/\",\"name\":\"Vagario\",\"description\":\"Seu Melhor site de Empregos e Vagas\",\"publisher\":{\"@id\":\"https:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/vagario.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6\",\"name\":\"vagario\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/vagario.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/83c677ba6122e98ab37e1afa2508ddf0de0cec8e3065582b3e503ef328b5b67a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/83c677ba6122e98ab37e1afa2508ddf0de0cec8e3065582b3e503ef328b5b67a?s=96&d=mm&r=g\",\"caption\":\"vagario\"},\"logo\":{\"@id\":\"https:\/\/vagario.com.br\/#\/schema\/person\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PREZUNIC ABRE VAGAS - ATENDENTES - 4 VAGAS - RIO DE JANEIRO - RJ","description":"PREZUNIC ABRE VAGAS - ATENDENTES - 4 VAGAS - RIO DE JANEIRO - RJ","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/","og_locale":"pt_BR","og_type":"article","og_title":"PREZUNIC ABRE VAGAS - ATENDENTES - 4 VAGAS - RIO DE JANEIRO - RJ","og_description":"PREZUNIC ABRE VAGAS - ATENDENTES - 4 VAGAS - RIO DE JANEIRO - RJ","og_url":"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/","og_site_name":"Vagario","article_published_time":"2021-03-03T13:12:03+00:00","og_image":[{"width":256,"height":256,"url":"https:\/\/vagario.com.br\/wp-content\/uploads\/2019\/12\/carioca256-1.png","type":"image\/png"}],"author":"vagario","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"vagario","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/#article","isPartOf":{"@id":"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/"},"author":{"name":"vagario","@id":"https:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6"},"headline":"PREZUNIC ABRE VAGAS &#8211; ATENDENTES &#8211; 4 VAGAS &#8211; RIO DE JANEIRO &#8211; RJ","datePublished":"2021-03-03T13:12:03+00:00","mainEntityOfPage":{"@id":"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/"},"wordCount":384,"publisher":{"@id":"https:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6"},"image":{"@id":"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/#primaryimage"},"thumbnailUrl":"https:\/\/vagario.com.br\/wp-content\/uploads\/2021\/01\/5.png","articleSection":["Atendente \/ Balconistas"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/","url":"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/","name":"PREZUNIC ABRE VAGAS - ATENDENTES - 4 VAGAS - RIO DE JANEIRO - RJ","isPartOf":{"@id":"https:\/\/vagario.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/#primaryimage"},"image":{"@id":"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/#primaryimage"},"thumbnailUrl":"https:\/\/vagario.com.br\/wp-content\/uploads\/2021\/01\/5.png","datePublished":"2021-03-03T13:12:03+00:00","description":"PREZUNIC ABRE VAGAS - ATENDENTES - 4 VAGAS - RIO DE JANEIRO - RJ","breadcrumb":{"@id":"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/#primaryimage","url":"https:\/\/vagario.com.br\/wp-content\/uploads\/2021\/01\/5.png","contentUrl":"https:\/\/vagario.com.br\/wp-content\/uploads\/2021\/01\/5.png","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/vagario.com.br\/index.php\/2021\/03\/03\/prezunic-abre-vagas-atendentes-4-vagas-rio-de-janeiro-rj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/vagario.com.br\/"},{"@type":"ListItem","position":2,"name":"PREZUNIC ABRE VAGAS &#8211; ATENDENTES &#8211; 4 VAGAS &#8211; RIO DE JANEIRO &#8211; RJ"}]},{"@type":"WebSite","@id":"https:\/\/vagario.com.br\/#website","url":"https:\/\/vagario.com.br\/","name":"Vagario","description":"Seu Melhor site de Empregos e Vagas","publisher":{"@id":"https:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vagario.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6","name":"vagario","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/vagario.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/83c677ba6122e98ab37e1afa2508ddf0de0cec8e3065582b3e503ef328b5b67a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83c677ba6122e98ab37e1afa2508ddf0de0cec8e3065582b3e503ef328b5b67a?s=96&d=mm&r=g","caption":"vagario"},"logo":{"@id":"https:\/\/vagario.com.br\/#\/schema\/person\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/116060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=116060"}],"version-history":[{"count":1,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/116060\/revisions"}],"predecessor-version":[{"id":116061,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/116060\/revisions\/116061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/media\/115416"}],"wp:attachment":[{"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=116060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=116060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=116060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}