{"id":112097,"date":"2020-07-22T10:18:25","date_gmt":"2020-07-22T13:18:25","guid":{"rendered":"http:\/\/vagario.com.br\/?p=112097"},"modified":"2020-07-22T10:18:25","modified_gmt":"2020-07-22T13:18:25","slug":"papelaria-abre-vagas-atendentes-gavea-rj","status":"publish","type":"post","link":"https:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/","title":{"rendered":"PAPELARIA ABRE VAGAS &#8211; ATENDENTES &#8211; GAVEA &#8211; RJ"},"content":{"rendered":"<p><span style=\"font-family: 'arial black', sans-serif;\"><strong>REQUERIMENTOS E INFORMA\u00c7\u00d5ES DA VAGA:<\/strong><\/span><\/p>\n<p>Descri\u00e7\u00e3o da Empresa: Empresa no ramo de com\u00e9rcio varejista (Papelaria) contrata: Cargo: Auxiliar de Vendas Vagas em aberto: 1 Especifica\u00e7\u00f5es do cargo: Atendimento ao cliente, reposi\u00e7\u00e3o de mercadoria, controle de estoque, efetuar cadastramento dos clientes e pedidos. Habilidades: Boa comunica\u00e7\u00e3o, ser organizado, relacionamento com o cliente, disposi\u00e7\u00e3o para aprender sobre os produtos, e conhecimento do pacote office ser\u00e1 um diferencial. Bairro: G\u00e1vea Cidade: Rio de Janeiro Benef\u00edcios: VT Remunera\u00e7\u00e3o: R$ 1.045,00 Hor\u00e1rio de Trabalho:\u00a0\u00a0a combinar Regime:CLT In\u00edcio Imediato Jornada de trabalho: segunda-feira \u00e0 domingo, com uma folga semanal.<\/p>\n<p><span style=\"font-family: 'arial black', sans-serif;\"><strong>CADASTRE O SEU CURR\u00cdCULO:<\/strong><\/span><br \/>\n<input type='hidden' bg_collapse_expand='6a046baed568b4044163212' value='6a046baed568b4044163212'><input type='hidden' id='bg-show-more-text-6a046baed568b4044163212' value='Quero me Candidatar'><input type='hidden' id='bg-show-less-text-6a046baed568b4044163212' value='Fechar'><button id='bg-showmore-action-6a046baed568b4044163212' class='bg-showmore-plg-button bg-orange-button  '   style=\" color:#4a4949;\">Quero me Candidatar<\/button><div id='bg-showmore-hidden-6a046baed568b4044163212' >Para se candidatar a vaga clique em: <a href=\"mailto:portaldocandidatorj@gmail.com\">portaldocandidatorj@gmail.com<\/a> <\/div>\n<p><em><strong>Todas as vagas aqui publicadas como informamos em nossos termos de uso, s\u00e3o de COMPLETA RESPONSABILIDADE dos contratantes\/anunciantes, O RIOVAGA RJ<\/strong><\/em><em><strong>\u00a0n\u00e3o<\/strong><\/em><em><strong>\u00a0 entra em contato com nenhuma empresa para verificar a veracidade das informa\u00e7\u00f5es fornecidas, a responsabilidade da verifica\u00e7\u00e3o das informa\u00e7\u00f5es e demais d\u00favidas das vagas \u00e9 do candidato interessado.<\/strong><\/em><\/p>\n<p><a href=\"whatsapp:\/\/send?text=&quot;RioVaga - Empregos e Vagas Rio de Janeiro - Clique no link para instalar e se candidatar as vagas:&quot;https:\/\/play.google.com\/store\/apps\/details?id=com.riovaga\"><br \/>\nCompartilhe essa vaga com um amigo do Whatsapp &#8211; Clicando Aqui!!<br \/>\n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>REQUERIMENTOS E INFORMA\u00c7\u00d5ES DA VAGA: Descri\u00e7\u00e3o da Empresa: Empresa no ramo de com\u00e9rcio varejista (Papelaria) contrata: Cargo: Auxiliar de Vendas<\/p>\n","protected":false},"author":1,"featured_media":858,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-112097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atendente-balconistas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PAPELARIA ABRE VAGAS - ATENDENTES - GAVEA - RJ<\/title>\n<meta name=\"description\" content=\"PAPELARIA ABRE VAGAS - ATENDENTES - GAVEA - RJ\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PAPELARIA ABRE VAGAS - ATENDENTES - GAVEA - RJ\" \/>\n<meta property=\"og:description\" content=\"PAPELARIA ABRE VAGAS - ATENDENTES - GAVEA - RJ\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/\" \/>\n<meta property=\"og:site_name\" content=\"Vagario\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-22T13:18:25+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/vagario.com.br\/wp-content\/uploads\/2019\/12\/carioca256-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"256\" \/>\n\t<meta property=\"og:image:height\" content=\"256\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"vagario\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vagario\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/\"},\"author\":{\"name\":\"vagario\",\"@id\":\"http:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6\"},\"headline\":\"PAPELARIA ABRE VAGAS &#8211; ATENDENTES &#8211; GAVEA &#8211; RJ\",\"datePublished\":\"2020-07-22T13:18:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/\"},\"wordCount\":211,\"publisher\":{\"@id\":\"http:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6\"},\"image\":{\"@id\":\"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/vagario.com.br\/wp-content\/uploads\/2019\/12\/riovagafoto.png\",\"articleSection\":[\"Atendente \/ Balconistas\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/\",\"url\":\"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/\",\"name\":\"PAPELARIA ABRE VAGAS - ATENDENTES - GAVEA - RJ\",\"isPartOf\":{\"@id\":\"http:\/\/vagario.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/vagario.com.br\/wp-content\/uploads\/2019\/12\/riovagafoto.png\",\"datePublished\":\"2020-07-22T13:18:25+00:00\",\"description\":\"PAPELARIA ABRE VAGAS - ATENDENTES - GAVEA - RJ\",\"breadcrumb\":{\"@id\":\"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/#primaryimage\",\"url\":\"https:\/\/vagario.com.br\/wp-content\/uploads\/2019\/12\/riovagafoto.png\",\"contentUrl\":\"https:\/\/vagario.com.br\/wp-content\/uploads\/2019\/12\/riovagafoto.png\",\"width\":351,\"height\":294},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/vagario.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PAPELARIA ABRE VAGAS &#8211; ATENDENTES &#8211; GAVEA &#8211; RJ\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/vagario.com.br\/#website\",\"url\":\"http:\/\/vagario.com.br\/\",\"name\":\"Vagario\",\"description\":\"Seu Melhor site de Empregos e Vagas\",\"publisher\":{\"@id\":\"http:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/vagario.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6\",\"name\":\"vagario\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/vagario.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/83c677ba6122e98ab37e1afa2508ddf0de0cec8e3065582b3e503ef328b5b67a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/83c677ba6122e98ab37e1afa2508ddf0de0cec8e3065582b3e503ef328b5b67a?s=96&d=mm&r=g\",\"caption\":\"vagario\"},\"logo\":{\"@id\":\"http:\/\/vagario.com.br\/#\/schema\/person\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PAPELARIA ABRE VAGAS - ATENDENTES - GAVEA - RJ","description":"PAPELARIA ABRE VAGAS - ATENDENTES - GAVEA - RJ","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/","og_locale":"pt_BR","og_type":"article","og_title":"PAPELARIA ABRE VAGAS - ATENDENTES - GAVEA - RJ","og_description":"PAPELARIA ABRE VAGAS - ATENDENTES - GAVEA - RJ","og_url":"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/","og_site_name":"Vagario","article_published_time":"2020-07-22T13:18:25+00:00","og_image":[{"width":256,"height":256,"url":"http:\/\/vagario.com.br\/wp-content\/uploads\/2019\/12\/carioca256-1.png","type":"image\/png"}],"author":"vagario","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"vagario","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/#article","isPartOf":{"@id":"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/"},"author":{"name":"vagario","@id":"http:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6"},"headline":"PAPELARIA ABRE VAGAS &#8211; ATENDENTES &#8211; GAVEA &#8211; RJ","datePublished":"2020-07-22T13:18:25+00:00","mainEntityOfPage":{"@id":"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/"},"wordCount":211,"publisher":{"@id":"http:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6"},"image":{"@id":"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/#primaryimage"},"thumbnailUrl":"https:\/\/vagario.com.br\/wp-content\/uploads\/2019\/12\/riovagafoto.png","articleSection":["Atendente \/ Balconistas"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/","url":"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/","name":"PAPELARIA ABRE VAGAS - ATENDENTES - GAVEA - RJ","isPartOf":{"@id":"http:\/\/vagario.com.br\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/#primaryimage"},"image":{"@id":"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/#primaryimage"},"thumbnailUrl":"https:\/\/vagario.com.br\/wp-content\/uploads\/2019\/12\/riovagafoto.png","datePublished":"2020-07-22T13:18:25+00:00","description":"PAPELARIA ABRE VAGAS - ATENDENTES - GAVEA - RJ","breadcrumb":{"@id":"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/#primaryimage","url":"https:\/\/vagario.com.br\/wp-content\/uploads\/2019\/12\/riovagafoto.png","contentUrl":"https:\/\/vagario.com.br\/wp-content\/uploads\/2019\/12\/riovagafoto.png","width":351,"height":294},{"@type":"BreadcrumbList","@id":"http:\/\/vagario.com.br\/index.php\/2020\/07\/22\/papelaria-abre-vagas-atendentes-gavea-rj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/vagario.com.br\/"},{"@type":"ListItem","position":2,"name":"PAPELARIA ABRE VAGAS &#8211; ATENDENTES &#8211; GAVEA &#8211; RJ"}]},{"@type":"WebSite","@id":"http:\/\/vagario.com.br\/#website","url":"http:\/\/vagario.com.br\/","name":"Vagario","description":"Seu Melhor site de Empregos e Vagas","publisher":{"@id":"http:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vagario.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"http:\/\/vagario.com.br\/#\/schema\/person\/54813f918e46846eb68de55fc26439d6","name":"vagario","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/vagario.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/83c677ba6122e98ab37e1afa2508ddf0de0cec8e3065582b3e503ef328b5b67a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83c677ba6122e98ab37e1afa2508ddf0de0cec8e3065582b3e503ef328b5b67a?s=96&d=mm&r=g","caption":"vagario"},"logo":{"@id":"http:\/\/vagario.com.br\/#\/schema\/person\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/112097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=112097"}],"version-history":[{"count":1,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/112097\/revisions"}],"predecessor-version":[{"id":112098,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/posts\/112097\/revisions\/112098"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/media\/858"}],"wp:attachment":[{"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=112097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=112097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vagario.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=112097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}